{"id":39968,"date":"2025-10-17T08:49:03","date_gmt":"2025-10-17T06:49:03","guid":{"rendered":"https:\/\/vcp.de\/pfadfinden\/?p=39968"},"modified":"2025-10-17T08:49:26","modified_gmt":"2025-10-17T06:49:26","slug":"faraway","status":"publish","type":"post","link":"https:\/\/vcp.de\/pfadfinden\/buchecke\/faraway\/","title":{"rendered":"F\u00fcr euch gespielt: FARAWAY"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">2-6 Spieler*innen, ab 10 Jahren<br>\u201eFaraway\u201c ist ein Kartenspiel f\u00fcr 2\u20136 Personen ab 10 Jahren. Acht Runden lang spielt ihr Regionskarten von links nach rechts in eure Auslage \u2013 jede zeigt Landschaften, Bewohner und Aufgaben. Gewertet werden am Ende die erf\u00fcllten Aufgaben r\u00fcckw\u00e4rts, also von rechts nach links. Wer geschickt plant, hat genau die Bedingungen im richtigen Moment erf\u00fcllt. Au\u00dferdem k\u00f6nnt ihr Heiligt\u00fcmer entdecken, die Bonuspunkte und neue M\u00f6glichkeiten bringen. \u201eFaraway\u201c ist schnell erkl\u00e4rt, taktisch kniffl ig und immer wieder \u00fcberraschend. Ein atmosph\u00e4risches Abenteuer, das Gelegenheitsspieler wie Strategen gleicherma\u00dfen begeistert. Das Spiel kombiniert klare Regeln mit spannender Denkarbeit und viel Abwechslung. Durch kurze Dauer, starke Illustrationen und hohen Wiederspielreiz ist \u201eFaraway\u201c ein echter Geheimtipp \u2013 strategisch, sch\u00f6n und \u00fcberraschend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201eFaraway\u201c ist ein Kartenspiel f\u00fcr 2\u20136 Personen ab 10 Jahren. Acht Runden lang spielt ihr Regionskarten von links nach rechts in eure Auslage \u2013 jede zeigt Landschaften, Bewohner und Aufgaben. Gewertet werden am Ende die erf\u00fcllten Aufgaben r\u00fcckw\u00e4rts, also von rechts nach links. Wer geschickt plant, hat genau die Bedingungen im richtigen Moment erf\u00fcllt. Au\u00dferdem k\u00f6nnt ihr Heiligt\u00fcmer entdecken, die Bonuspunkte und neue M\u00f6glichkeiten bringen. \u201eFaraway\u201c ist schnell erkl\u00e4rt, taktisch kniffl ig und immer wieder \u00fcberraschend. Ein atmosph\u00e4risches Abenteuer, das Gelegenheitsspieler wie Strategen gleicherma\u00dfen begeistert. Das Spiel kombiniert klare Regeln mit spannender Denkarbeit und viel Abwechslung. Durch kurze Dauer, starke Illustrationen und hohen Wiederspielreiz ist \u201eFaraway\u201c ein echter Geheimtipp \u2013 strategisch, sch\u00f6n und \u00fcberraschend.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infos zum Spiel:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kosmos, 2024<br>Autor*innen: Johannes Goupy,<br>Corentin Lebrat, Maxime Morin<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2-6 Spieler*innen, ab 10 Jahren\u201eFaraway\u201c ist ein Kartenspiel f\u00fcr 2\u20136 Personen ab 10 Jahren. Acht Runden lang spielt ihr Regionskarten von links nach rechts in eure Auslage \u2013 jede zeigt Landschaften, Bewohner und Aufgaben. Gewertet werden am Ende die erf\u00fcllten Aufgaben r\u00fcckw\u00e4rts, also von rechts nach links. Wer geschickt plant, hat genau die Bedingungen im [&hellip;]<\/p>\n","protected":false},"author":98,"featured_media":39969,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[419,48],"tags":[],"class_list":["post-39968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auf-neuem-pfad","category-buchecke"],"acf":[],"_links":{"self":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/39968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/comments?post=39968"}],"version-history":[{"count":2,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/39968\/revisions"}],"predecessor-version":[{"id":40014,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/39968\/revisions\/40014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media\/39969"}],"wp:attachment":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media?parent=39968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/categories?post=39968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/tags?post=39968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}