{"id":39960,"date":"2025-10-17T08:53:32","date_gmt":"2025-10-17T06:53:32","guid":{"rendered":"https:\/\/vcp.de\/pfadfinden\/?p=39960"},"modified":"2025-10-17T08:53:33","modified_gmt":"2025-10-17T06:53:33","slug":"questors-die-weltenretter","status":"publish","type":"post","link":"https:\/\/vcp.de\/pfadfinden\/buchecke\/questors-die-weltenretter\/","title":{"rendered":"Questors &#8211; Die Weltenretter"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Gelesen von Maiken Cramer<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Questors wurden dazu geschaffen, die drei Welten vor ihrem bevorstehenden Untergang zu bewahren. Jede Welt sollte einen Helden hervorbringen, der die St\u00e4rken und Ideale seiner Heimat in sich vereint. Ein Krieger aus Kir, ein Vision\u00e4r mit metaphysischen F\u00e4higkeiten von Dalrodia und ein strategisches Genie aus Trentor. Auf dem Papier das perfekte Team, wenn sich nicht eine dunkle Macht eingemischt h\u00e4tte. Jetzt m\u00fcssen unsere jungen Questors sich nicht nur v\u00f6llig unvorbereitet auf die Suche nach den Gegenst\u00e4nden der Macht machen, die angeblich die Schl\u00fcssel zur Rettung der Welten sind, sondern sich auch ihren eigenen \u00c4ngsten und den Vorurteilen ihrer Welt stellen. Was mich am Roman von Joan Lennon so fasziniert hat, war, dass sie es geschafft hat, eine mitrei\u00dfende Geschichte ohne einen gr\u00f6\u00dferen physischen Konflikt zu schreiben. Auch wenn das Buch viele spannende Kampf- und Actionszenen beinhaltet, handelt die wahre Geschichte davon, wie die Welten von ihrem eigenen System zerst\u00f6rt wurden und die Questors es durch das \u00dcberwinden und Hinterfragen ihrer Ideale schaffen, zusammen einen Platz f\u00fcr sich zu finden. Viel Spa\u00df beim Lesen und beim Eintauchen in die drei Welten! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infos zum Buch:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Autor*in: Joan Lennon<br>Verlag: cbj Kinderb\u00fccher Verlag<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gelesen von Maiken Cramer Die Questors wurden dazu geschaffen, die drei Welten vor ihrem bevorstehenden Untergang zu bewahren. Jede Welt sollte einen Helden hervorbringen, der die St\u00e4rken und Ideale seiner Heimat in sich vereint. Ein Krieger aus Kir, ein Vision\u00e4r mit metaphysischen F\u00e4higkeiten von Dalrodia und ein strategisches Genie aus Trentor. Auf dem Papier das [&hellip;]<\/p>\n","protected":false},"author":98,"featured_media":39961,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[419,48],"tags":[],"class_list":["post-39960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auf-neuem-pfad","category-buchecke"],"acf":[],"_links":{"self":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/39960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/users\/98"}],"replies":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/comments?post=39960"}],"version-history":[{"count":2,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/39960\/revisions"}],"predecessor-version":[{"id":39963,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/39960\/revisions\/39963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media\/39961"}],"wp:attachment":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media?parent=39960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/categories?post=39960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/tags?post=39960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}