{"id":24807,"date":"2022-03-02T19:00:47","date_gmt":"2022-03-02T18:00:47","guid":{"rendered":"https:\/\/www.vcp.de\/pfadfinden\/?p=24807"},"modified":"2024-11-28T15:04:15","modified_gmt":"2024-11-28T14:04:15","slug":"50-jahre-ff","status":"publish","type":"post","link":"https:\/\/vcp.de\/pfadfinden\/allgemein\/50-jahre-ff\/","title":{"rendered":"50 Jahre F&#038;F"},"content":{"rendered":"\n<p>50 Jahre F&amp;F! Das Jubil\u00e4um unseres Ausr\u00fcsters bietet Gelegenheit, einmal im VCP-Bundesarchiv und bei F&amp;F selbst nach seinen Anf\u00e4ngen zu forschen.<\/p>\n\n\n\n<p>Zum M\u00e4rz 1972 wurde F&amp;F als gemeinsame Firma von CPD und dem CVJM gegr\u00fcndet. Den &#8222;Vertrieb von Artikeln f\u00fcr Freizeit, Fahrt und Lager, Sport und Spiel&#8220; sollte F&amp;F f\u00fcr die Verb\u00e4nde gew\u00e4hrleisten. Jeder Verband hatte davor sein eigenes Unternehmen, das der CPD nannte sich &#8222;R\u00fcsthaus und Pfadverlag GmbH&#8220;, &#8222;Wirtschaftsstelle&#8220; das der CVJM. In einem damaligen Rundschreiben hie\u00df es: &#8222;Diese neue Firma wird nicht nur durch rationellere Arbeitsm\u00f6glichkeiten Kosten sparen, sondern auch durch gr\u00f6\u00dfere Eink\u00e4ufe und einen schnelleren Lagerumschlag leistungsf\u00e4higer werden&#8230;&#8220; Tats\u00e4chlich liefen die Gesch\u00e4fte beider Ausr\u00fcster vor der Zusammenarbeit nicht gut und da sich viele Angebote \u00fcberschnitten, war eine gemeinsame Firma eigentlich logisch. Das R\u00fcsthaus der CPD hatte \u00fcbrigens 1970 die Wirtschaftsstelle des EMP \u00fcbernommen und belieferte auch die BCPlerinnen mit Ausr\u00fcstungsgegenst\u00e4nden. 2007 wurden die CVJM-Anteile dann vom VCP \u00fcbernommen, der seitdem alleiniger Gesellschafter an F&amp;F ist und wir k\u00f6nnen also seitdem zurecht von &#8222;unserem&#8220; Ausr\u00fcster F&amp;F sprechen.<\/p>\n\n\n\n<p>Obwohl beide Verb\u00e4nde damals ihren Sitz in Nordhessen hatten &#8211; der CVJM in Kassel und die CPD in Bad Wildungen, wurde die Firma der Einfachheit halber in den R\u00e4umlichkeiten und mit dem Personal des CPD-R\u00fcsthauses in Ulm er\u00f6ffnet. Im Jahr 2000 dann zog F&amp;F um nach Illertissen, um neben dem Versandhandel Waren auch in einem gro\u00dfz\u00fcgigeren Ladengesch\u00e4ft anbieten zu k\u00f6nnen. Der Umzug nach Kaufungen, in die N\u00e4he unserer Bundeszentrale, erfolgte dann 2012.<\/p>\n\n\n\n<p>Kataloge, die per Post verschickt und Sendungen beigelegt wurden, waren im Vor-Internetzeitalter die haupts\u00e4chliche Werbem\u00f6glichkeit des Versandhandels, neben Anzeigen in Zeitungen und Zeitschriften. Werbung wurde haupts\u00e4chlich in Publikationen der Bundeszentrale und Landesverb\u00e4nde geschaltet. Neben Hauptkatalogen gab es anfangs immer wieder auch Werbeaktionen zu Sonderposten oder mit saisonalen Angeboten. Ein paar Zahlen habe ich dazu gefunden: 1979 betraf die Auflage des Hauptkatalogs 20.000 Exemplare, 1980 &#8211; ab da war der Katalog dann im DIN A4-Format &#8211; 27.000 und eine Sonderpostenwerbung brachte es 1983 auf 33.000 zu verschickende Exemplare. Mit Einrichtung eines Internetshops 1998 verschob sich dann allm\u00e4hlich die Werbung und nat\u00fcrlich ver\u00e4nderte sich das Angebot der angebotenen Waren \u00fcber die Zeit.<\/p>\n\n\n\n<p>Heute bietet <a href=\"https:\/\/www.fahrtenbedarf.de\/\" target=\"_blank\" rel=\"noopener\">F&amp;F<\/a> Verbandsbedarf von<a href=\"https:\/\/www.vcp.de\/\" target=\"_blank\" rel=\"noopener\"> VCP,<\/a> <a href=\"https:\/\/www.cvjm.de\/\" target=\"_blank\" rel=\"noopener\">CVJM<\/a>, der <a href=\"https:\/\/www.malteserjugend.de\/\" target=\"_blank\" rel=\"noopener\">Malteser Jugend<\/a>, der<a href=\"https:\/\/wanderjugend.de\/deutsche-wanderjugend\" target=\"_blank\" rel=\"noopener\"> Deutschen Wanderjugend<\/a> und der <a href=\"https:\/\/www.aej.de\/startseite\" target=\"_blank\" rel=\"noopener\">Evangelischen Jugend<\/a> an. Ihr k\u00f6nnt dort eure Ausr\u00fcstung f\u00fcr Lager und Fahrten erwerben, f\u00fcr Freizeit-, Sport und Spielaktivit\u00e4ten und vieles mehr. F&amp;F findet ihr mit einem eigenen Kiosk auf dem <a href=\"https:\/\/www.vcp-bundeszeltplatz.de\/\" target=\"_blank\" rel=\"noopener\">BZG<\/a>, auf dem Bundeslager und anderen kleineren und gr\u00f6\u00dferen Veranstaltungen, nicht nur denen des VCP.<\/p>\n\n\n\n<p>Wenn ihr Lust habt, in alten Katalogen zu st\u00f6bern, dann schaut doch mal hier vorbei:<\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/go.vcp.de\/rsthausundpfadverlagkatalog-1971\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-issuu wp-block-embed-issuu\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iRXJzdGVyIEYmYW1wO0YtSGF1cHRrYXRhbG9nIHZvbiAxOTcyIiBzcmM9Imh0dHBzOi8vZS5pc3N1dS5jb20vZW1iZWQuaHRtbD91PXZjcC5kZSZkPWZfZi5rYXRhbG9nLTE5NzIiIHN0eWxlPSJib3JkZXI6bm9uZTsgd2lkdGg6IDY0MHB4OyBoZWlnaHQ6IDQ5MXB4OyIgYWxsb3c9ImNsaXBib2FyZC13cml0ZSxhbGxvdy10b3AtbmF2aWdhdGlvbixhbGxvdy10b3AtbmF2aWdhdGlvbi1ieS11c2VyLWFjdGl2YXRpb24sYWxsb3ctZG93bmxvYWRzLGFsbG93LXNjcmlwdHMsYWxsb3ctc2FtZS1vcmlnaW4sYWxsb3ctcG9wdXBzLGFsbG93LW1vZGFscyxhbGxvdy1wb3B1cHMtdG8tZXNjYXBlLXNhbmRib3gsYWxsb3ctZm9ybXMiICBhbGxvd2Z1bGxzY3JlZW49InRydWUiPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-issuu wp-block-embed-issuu\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iRiZhbXA7Ri1IYXVwdGthdGFsb2cgdm9uIDE5NzMiIHNyYz0iaHR0cHM6Ly9lLmlzc3V1LmNvbS9lbWJlZC5odG1sP3U9dmNwLmRlJmQ9Zl9mLmthdGFsb2ctMTk3MyIgc3R5bGU9ImJvcmRlcjpub25lOyB3aWR0aDogNjQwcHg7IGhlaWdodDogNDkxcHg7IiBhbGxvdz0iY2xpcGJvYXJkLXdyaXRlLGFsbG93LXRvcC1uYXZpZ2F0aW9uLGFsbG93LXRvcC1uYXZpZ2F0aW9uLWJ5LXVzZXItYWN0aXZhdGlvbixhbGxvdy1kb3dubG9hZHMsYWxsb3ctc2NyaXB0cyxhbGxvdy1zYW1lLW9yaWdpbixhbGxvdy1wb3B1cHMsYWxsb3ctbW9kYWxzLGFsbG93LXBvcHVwcy10by1lc2NhcGUtc2FuZGJveCxhbGxvdy1mb3JtcyIgIGFsbG93ZnVsbHNjcmVlbj0idHJ1ZSI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-issuu wp-block-embed-issuu\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iRiZhbXA7Ri1IYXVwdGthdGFsb2cgdm9uIDE5NzQiIHNyYz0iaHR0cHM6Ly9lLmlzc3V1LmNvbS9lbWJlZC5odG1sP3U9dmNwLmRlJmQ9Zl9mLmthdGFsb2ctMTk3NCIgc3R5bGU9ImJvcmRlcjpub25lOyB3aWR0aDogNjQwcHg7IGhlaWdodDogNDkxcHg7IiBhbGxvdz0iY2xpcGJvYXJkLXdyaXRlLGFsbG93LXRvcC1uYXZpZ2F0aW9uLGFsbG93LXRvcC1uYXZpZ2F0aW9uLWJ5LXVzZXItYWN0aXZhdGlvbixhbGxvdy1kb3dubG9hZHMsYWxsb3ctc2NyaXB0cyxhbGxvdy1zYW1lLW9yaWdpbixhbGxvdy1wb3B1cHMsYWxsb3ctbW9kYWxzLGFsbG93LXBvcHVwcy10by1lc2NhcGUtc2FuZGJveCxhbGxvdy1mb3JtcyIgIGFsbG93ZnVsbHNjcmVlbj0idHJ1ZSI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-issuu wp-block-embed-issuu\"><div class=\"wp-block-embed__wrapper\">\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iRiZhbXA7Ri1IYXVwdGthdGFsb2cgdm9uIDE5NzUiIHNyYz0iaHR0cHM6Ly9lLmlzc3V1LmNvbS9lbWJlZC5odG1sP3U9dmNwLmRlJmQ9Zl9mLmthdGFsb2ctMTk3NSIgc3R5bGU9ImJvcmRlcjpub25lOyB3aWR0aDogNjQwcHg7IGhlaWdodDogNDkxcHg7IiBhbGxvdz0iY2xpcGJvYXJkLXdyaXRlLGFsbG93LXRvcC1uYXZpZ2F0aW9uLGFsbG93LXRvcC1uYXZpZ2F0aW9uLWJ5LXVzZXItYWN0aXZhdGlvbixhbGxvdy1kb3dubG9hZHMsYWxsb3ctc2NyaXB0cyxhbGxvdy1zYW1lLW9yaWdpbixhbGxvdy1wb3B1cHMsYWxsb3ctbW9kYWxzLGFsbG93LXBvcHVwcy10by1lc2NhcGUtc2FuZGJveCxhbGxvdy1mb3JtcyIgIGFsbG93ZnVsbHNjcmVlbj0idHJ1ZSI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Sie sehen gerade einen Platzhalterinhalt von <strong>Standard<\/strong>. Um auf den eigentlichen Inhalt zuzugreifen, klicken Sie auf den Button unten. Bitte beachten Sie, dass dabei Daten an Drittanbieter weitergegeben werden.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Inhalt entsperren<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Erforderlichen Service akzeptieren und Inhalte entsperren<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Weitere Informationen<\/a> <\/div><\/div>\n<\/div><\/figure>\n\n\n\n<p>Au\u00dferdem hat F&amp;F selbst auf seiner Website einiges zu <a href=\"https:\/\/www.fahrtenbedarf.de\/cgi-bin\/shop\/iboshop.cgi?show1210990210,740516708377985\" target=\"_blank\" rel=\"noopener\">seiner Geschichte<\/a> geschrieben, schaut doch mal dort vorbei!<\/p>\n\n\n\n<p>Text: VCP\/Bernd Eichhorn<\/p>\n\n\n<!-- TEST -->\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03e93a31005&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03e93a31005\" class=\"wp-block-image aligncenter size-thumbnail wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf-150x150.png\" alt=\"50 Jahre Freizeit- und Fahrtenbedarf Foto: VCP\/Hanna R\u00f6wer\" class=\"wp-image-24818\" srcset=\"https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf-150x150.png 150w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf-300x300.png 300w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf-1024x1024.png 1024w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf-768x768.png 768w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf-45x45.png 45w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2022\/03\/Jahre-Freizeit-und-Fahrtnbedarf.png 1080w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Vergr\u00f6\u00dfern\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Foto: VCP\/Hanna R\u00f6wer<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>50 Jahre F&amp;F! Das Jubil\u00e4um unseres Ausr\u00fcsters bietet Gelegenheit, einmal im VCP-Bundesarchiv und bei F&amp;F selbst nach seinen Anf\u00e4ngen zu forschen. Zum M\u00e4rz 1972 wurde F&amp;F als gemeinsame Firma von CPD und dem CVJM gegr\u00fcndet. Den &#8222;Vertrieb von Artikeln f\u00fcr Freizeit, Fahrt und Lager, Sport und Spiel&#8220; sollte F&amp;F f\u00fcr die Verb\u00e4nde gew\u00e4hrleisten. Jeder Verband [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":24818,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1,23],"tags":[576,577],"class_list":["post-24807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-vcp-bundesarchiv","tag-bundesarchiv","tag-vcp-bundesarchiv"],"acf":[],"_links":{"self":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/24807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/comments?post=24807"}],"version-history":[{"count":1,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/24807\/revisions"}],"predecessor-version":[{"id":37653,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/posts\/24807\/revisions\/37653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media\/24818"}],"wp:attachment":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media?parent=24807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/categories?post=24807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/tags?post=24807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}