{"id":32621,"date":"2025-11-30T13:27:00","date_gmt":"2025-11-30T12:27:00","guid":{"rendered":"https:\/\/www.vcp.de\/pfadfinden\/?page_id=32621"},"modified":"2026-01-27T09:52:40","modified_gmt":"2026-01-27T08:52:40","slug":"aufarbeitung","status":"publish","type":"page","link":"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/","title":{"rendered":"Aufarbeitung"},"content":{"rendered":"<ul class=\"wp-block-latest-posts__list wp-block-latest-posts is-layout-flow wp-block-latest-posts-is-layout-flow\"><li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/vcp.de\/pfadfinden\/bundeslager\/jurtengesprach-aufarbeitung-bula\/\" aria-label=\"Aufarbeitung: Schon alles gesagt? Ein Jurtengespr\u00e4ch auf dem BuLa\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/07\/20250503-110651_Knuepfwochenende-2025_kb-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/vcp.de\/pfadfinden\/bundeslager\/jurtengesprach-aufarbeitung-bula\/\">Aufarbeitung: Schon alles gesagt? Ein Jurtengespr\u00e4ch auf dem BuLa<\/a><div class=\"wp-block-latest-posts__post-excerpt\">Im Januar wurde die unabh\u00e4ngige Aufarbeitungsstudie zu sexualisierter Gewalt im VCP ver\u00f6ffentlicht. Viele Fragen bleiben: Was bedeutet das f\u00fcr uns als Verband? Was k\u00f6nnen wir daraus lernen? Und wie schaffen wir eine Kultur, in der\u2026\u00a0<a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/vcp.de\/pfadfinden\/bundeslager\/jurtengesprach-aufarbeitung-bula\/\" rel=\"noopener\">Weiterlesen<span class=\"screen-reader-text\">: Aufarbeitung: Schon alles gesagt? Ein Jurtengespr\u00e4ch auf dem BuLa<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/fachkonferenz-aufarbeitung\/\" aria-label=\"Fachkonferenz Aufarbeitung\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" srcset=\"https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-150x150.png 150w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-300x300.png 300w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-1024x1024.png 1024w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-768x768.png 768w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-1536x1536.png 1536w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-2048x2048.png 2048w, https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/VCP-Waldla\u2560euferzeichen-Tafeln_Seite_29-750x750.png 750w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/fachkonferenz-aufarbeitung\/\">Fachkonferenz Aufarbeitung<\/a><div class=\"wp-block-latest-posts__post-excerpt\">Liebe Pfadfinder*innen, liebe Engagierte im VCP, liebe Wegbegleiter*innen, Die Aufarbeitungsstudie des VCP ist ver\u00f6ffentlicht und sie stellt uns als Verband Fragen:Wie gehen wir im VCP mit Erfahrungen um, die uns herausfordern \u2013 pers\u00f6nlich, als Gruppen,\u2026\u00a0<a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/fachkonferenz-aufarbeitung\/\" rel=\"noopener\">Weiterlesen<span class=\"screen-reader-text\">: Fachkonferenz Aufarbeitung<\/span><\/a><\/div><\/li>\n<li><div class=\"wp-block-latest-posts__featured-image alignleft\"><a href=\"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/veroeffentlichung-der-aufarbeitungsstudie-video-der-pressekonferenz\/\" aria-label=\"Ver\u00f6ffentlichung der Aufarbeitungsstudie: Video der Pressekonferenz\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/vcp.de\/pfadfinden\/wp-content\/uploads\/2026\/01\/1769608953498-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-post-image\" alt=\"\" style=\"\" \/><\/a><\/div><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/veroeffentlichung-der-aufarbeitungsstudie-video-der-pressekonferenz\/\">Ver\u00f6ffentlichung der Aufarbeitungsstudie: Video der Pressekonferenz<\/a><div class=\"wp-block-latest-posts__post-excerpt\">Am 27. Januar 2026 wurde dem VCP die Aufarbeitungsstudie zu sexualisierter Gewalt im Verband \u00fcbergeben. Am selben Tag wurden der Presse die wichtigsten Fakten und Erkenntnisse in einer Live-Veranstaltung mitgeteilt. Den vollst\u00e4ndigen Mitschnitt dieser Pressekonferenz\u2026\u00a0<a class=\"wp-block-latest-posts__read-more\" href=\"https:\/\/vcp.de\/pfadfinden\/aufarbeitung\/veroeffentlichung-der-aufarbeitungsstudie-video-der-pressekonferenz\/\" rel=\"noopener\">Weiterlesen<span class=\"screen-reader-text\">: Ver\u00f6ffentlichung der Aufarbeitungsstudie: Video der Pressekonferenz<\/span><\/a><\/div><\/li>\n<\/ul>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201eAufarbeitung bedeutet: Konsequenzen f\u00fcr die Gegenwart ziehen und Erkenntnisse und Wissen f\u00fcr die Zukunft bewahren.\u201c<\/p>\n<cite>Unabh\u00e4ngige Kommission zur Aufarbeitung sexuellen Kindesmissbrauchs<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Die Aufarbeitung sexualisierter Gewalt in der Vergangenheit ist neben Pr\u00e4vention, Intervention und Hilfen ein zentraler Aspekt im Kampf gegen Missbrauch. Dem VCP ist es in seiner Vergangenheit nicht immer gelungen, seine Mitglieder vor sexualisierter Gewalt zu sch\u00fctzen. Dieser Verantwortung wollen wir uns stellen. In den vergangenen vier Jahren wurden vermehrt sogenannte \u201eAltf\u00e4lle\u201c bekannt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Was bedeutet Aufarbeitung?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Anders als in einem strafrechtlichen Verfahren geht es nicht darum, T\u00e4ter*innen zu identifizieren und zu verurteilen, da die F\u00e4lle oft bereits verj\u00e4hrt sind. Umso wichtiger ist es aber f\u00fcr Betroffene, dass ihr Leid dennoch gesehen und anerkannt wird. Dadurch kann die Organisation lernen, welche strukturellen Mechanismen in der Vergangenheit den Missbrauch erm\u00f6glicht haben und warum er \u00fcber einen so langen Zeitraum unentdeckt blieb. Aus diesen Erkenntnissen k\u00f6nnen dann notwendigen Konsequenzen f\u00fcr die Gegenwart gezogen werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wie funktioniert Aufarbeitung im VCP?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die unabh\u00e4ngige Aufarbeitung im VCP erfolgt mit wissenschaftlicher Begleitung durch das <a href=\"https:\/\/www.ipp-muenchen.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">IPP (Institut f\u00fcr Praxisforschung und Projektberatung)<\/a> und <a href=\"https:\/\/www.dissens.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dissens &#8211; Institut f\u00fcr Bildung und Forschung e.V.<\/a> Beide Kooperationspartner verf\u00fcgen \u00fcber jahrelange Expertise mit der wissenschaftlichen Aufarbeitung sexualisierter Gewalt in Institutionen. Die F\u00fchrung und Leitung des Aufarbeitungsprozesses obliegt den beiden Vertragspartnern. Die Institute \u00fcbernehmen die Verantwortung f\u00fcr das Forschungsdesign, die Auswahl der Zug\u00e4nge zum Forschungsfeld, die Auswahl der Quellen, die Datenerhebung sowie Datenauswertung.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-vcp-red\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.vcp.de\/pfadfinden\/aus-dem-verband\/achtsamundaktiv\/haeufige-fragen-zur-aufarbeitung-sexualisierter-gewalt-im-vcp\">Fragen und Antworten zur Aufarbeitung sexualisierter Gewalt im VCP<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Informationen zur Studie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Untersuchungszeitraum ist 1973 bis 2020. Der Aufarbeitungsprozess hat im November 2023 begonnen. Es wurden alle abgeschlossenen Interventionsf\u00e4lle in dem Aufarbeitungsprozess untersucht, um ein m\u00f6glichst ganzheitliches Bild zu erhalten. Unsere Absicht ist es, die Kultur des Schweigens in Bezug auf sexualisierte Gewalt in der Vergangenheit zu durchbrechen und eine Auseinandersetzung mit diesem Thema innerhalb des Verbands zu f\u00f6rdern. Dabei stehen die Belange von Betroffenen sexualisierter Gewalt im Mittelpunkt.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wie l\u00e4sst sich das Ph\u00e4nomen sexueller Missbrauch im VCP von 1973 bis 2020 beschreiben?<\/li>\n\n\n\n<li>Wer waren die T\u00e4ter*innen? Gab es T\u00e4ter*innennetzwerke?<\/li>\n\n\n\n<li>Welche kulturellen und strukturellen Faktoren haben sexuellen Missbrauch im VCP beg\u00fcnstigt?<\/li>\n\n\n\n<li>Wie sind die Verantwortungstr\u00e4ger*innen des VCP mit T\u00e4ter*innen und Betroffenen in der Vergangenheit umgegangen?<\/li>\n\n\n\n<li>Wie ist dieser Umgang mit T\u00e4ter*innen und Betroffenen im gesellschaftspolitisch-historischen Kontext und aus heutiger Perspektive zu bewerten?<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fachkongress zur Aufarbeitungsstudie&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Abschlussbericht der Aufarbeitungsstudie (Januar 2026) m\u00f6chten wir diesen insbesondere mit euch als Verband gemeinsam auf der Burg Rieneck in vielen verschiedenen Arbeitsgruppen besprechen. Der Fachkongress, um die n\u00e4heren Empfehlungen aus der wissenschaftlichen Studie gemeinsam mit den Forschungsinstituten und Vertreter*innen des Beirats zu besprechen, findet am 13.11. bis 15.11. 2026 auf der Burg Rieneck statt.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eAufarbeitung bedeutet: Konsequenzen f\u00fcr die Gegenwart ziehen und Erkenntnisse und Wissen f\u00fcr die Zukunft bewahren.\u201c Unabh\u00e4ngige Kommission zur Aufarbeitung sexuellen Kindesmissbrauchs Die Aufarbeitung sexualisierter Gewalt in der Vergangenheit ist neben Pr\u00e4vention, Intervention und Hilfen ein zentraler Aspekt im Kampf gegen Missbrauch. Dem VCP ist es in seiner Vergangenheit nicht immer gelungen, seine Mitglieder vor sexualisierter [&hellip;]<\/p>\n","protected":false},"author":52,"featured_media":30712,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-32621","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/pages\/32621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/comments?post=32621"}],"version-history":[{"count":27,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/pages\/32621\/revisions"}],"predecessor-version":[{"id":40414,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/pages\/32621\/revisions\/40414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media\/30712"}],"wp:attachment":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media?parent=32621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}