{"id":22060,"date":"2021-06-21T09:26:32","date_gmt":"2021-06-21T07:26:32","guid":{"rendered":"podlove-2021-06-18t09:22:56+00:00-b92f07e7c97d833"},"modified":"2021-06-21T09:26:32","modified_gmt":"2021-06-21T07:26:32","slug":"interview-mit-prof-dr-gunda-voigts-thema-gleichberechtigung-und-jamboree-korea-2023","status":"publish","type":"podcast","link":"https:\/\/vcp.de\/pfadfinden\/podcast\/interview-mit-prof-dr-gunda-voigts-thema-gleichberechtigung-und-jamboree-korea-2023\/","title":{"rendered":"Interview mit Prof. Dr. Gunda Voigts, Thema Gleichberechtigung und Jamboree Korea 2023"},"content":{"rendered":"\n\t\t\n            <div class=\"podlove-web-player intrinsic-ignore podlove-web-player-loading\" id=\"player-6a03f72d73fb2\"><root data-test=\"player--xl\" style=\"max-width:950px;min-width:260px;\">\n  <div class=\"tablet:px-6 tablet:pt-6 mobile:px-4 mobile:pt-4 flex flex-col\">\n    <div class=\"flex-col items-center mobile:flex tablet:hidden\">\n      <show-title class=\"text-sm\"><\/show-title>\n      <episode-title class=\"text-base mb-2\"><\/episode-title>\n      <subscribe-button class=\"mb-4 mobile:flex tablet:hidden\"><\/subscribe-button>\n      <poster class=\"rounded-sm w-48 shadow overflow-hidden\"><\/poster>\n      <divider class=\"w-full my-6\"><\/divider>\n    <\/div>\n\n    <div class=\"tablet:flex flex-grow\">\n      <div class=\"w-64 mobile:hidden tablet:block tablet:mr-6\">\n        <poster class=\"rounded-sm shadow overflow-hidden\"><\/poster>\n      <\/div>\n      <div class=\"w-full\">\n        <div class=\"hidden tablet:block\">\n          <show-title class=\"text-base\"><\/show-title>\n          <episode-title class=\"text-xl desktop:text-2xl\"><\/episode-title>\n          <divider class=\"w-full my-4\"><\/divider>\n        <\/div>\n        <div class=\"flex items-center justify-between\">\n          <div class=\"block\">\n            <play-state on=\"active\">\n              <speed-control class=\"flex items-center\"><\/speed-control>\n            <\/play-state>\n          <\/div>\n\n          <div class=\"flex\">\n            <play-state on=\"active\">\n              <chapter-previous class=\"mx-2 block\"><\/chapter-previous>\n            <\/play-state>\n            <play-state on=\"active\">\n              <step-backward class=\"mx-2 block\"><\/step-backward>\n            <\/play-state>\n\n            <play-button class=\"mx-2 block\" :label=\"$t('PLAYER.PLAY_EPISODE')\"><\/play-button>\n\n            <play-state on=\"active\">\n              <step-forward class=\"mx-2 block\"><\/step-forward>\n            <\/play-state>\n            <play-state on=\"active\">\n              <chapter-next class=\"mx-2 block\"><\/chapter-next>\n            <\/play-state>\n          <\/div>\n\n          <div class=\"block\">\n            <play-state on=\"active\">\n              <volume-control class=\"flex items-center\"><\/volume-control>\n            <\/play-state>\n          <\/div>\n        <\/div>\n        <div class=\"flex w-full\">\n          <progress-bar><\/progress-bar>\n        <\/div>\n        <div class=\"flex w-full -mt-2\">\n          <div class=\"w-3\/12 text-left\">\n            <timer-current class=\"text-sm\"><\/timer-current>\n          <\/div>\n          <div class=\"w-6\/12 text-center truncate\">\n            <play-state on=\"active\">\n              <current-chapter class=\"text-sm\"><\/current-chapter>\n            <\/play-state>\n          <\/div>\n          <div class=\"w-3\/12 text-right\">\n            <timer-duration class=\"text-sm\"><\/timer-duration>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n    <divider class=\"w-full mt-6 mb-3\"><\/divider>\n    <div class=\"flex justify-between\">\n      <div class=\"flex mobile:w-full tablet:w-3\/12 desktop:w-3\/12 justify-between\">\n        <tab-trigger tab=\"chapters\">\n          <icon type=\"chapter\"><\/icon>\n        <\/tab-trigger>\n        <tab-trigger tab=\"transcripts\">\n          <icon type=\"transcripts\"><\/icon>\n        <\/tab-trigger>\n        <tab-trigger tab=\"files\">\n          <icon type=\"download\"><\/icon>\n        <\/tab-trigger>\n        <tab-trigger tab=\"playlist\">\n          <icon type=\"playlist\"><\/icon>\n        <\/tab-trigger>\n        <tab-trigger tab=\"share\">\n          <icon type=\"share\"><\/icon>\n        <\/tab-trigger>\n      <\/div>\n      <subscribe-button class=\"mt-1 mobile:hidden tablet:flex\"><\/subscribe-button>\n    <\/div>\n  <\/div>\n  <div class=\"w-full relative overflow-hidden\">\n    <tab name=\"chapters\">\n      <tab-chapters><\/tab-chapters>\n    <\/tab>\n    <tab name=\"transcripts\">\n      <tab-transcripts><\/tab-transcripts>\n    <\/tab>\n    <tab name=\"files\">\n      <tab-files><\/tab-files>\n    <\/tab>\n    <tab name=\"playlist\">\n      <tab-playlist><\/tab-playlist>\n    <\/tab>\n    <tab name=\"share\">\n      <tab-share><\/tab-share>\n    <\/tab>\n    <tab-overflow><\/tab-overflow>\n  <\/div>\n  <error><\/error>\n<\/root>\n<\/div>\n            <script>\n              document.addEventListener(\"DOMContentLoaded\", function() {\n                var player = document.getElementById(\"player-6a03f72d73fb2\");\n                podlovePlayerCache.add([{\"url\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/wp-json\\\/podlove-web-player\\\/shortcode\\\/publisher\\\/22060\",\"data\":{\"version\":5,\"show\":{\"title\":\"Podcast Pfadfinden\",\"subtitle\":\"Pfadfinder*innen Podcast - Was macht der Verband Christlicher Pfadfinderinnen und Pfadfinder (VCP) eigentlich? Womit besch\\u00e4ftigen sich seine Mitglieder?\",\"summary\":\"Was macht der Verband Christlicher Pfadfinderinnen und Pfadfinder (VCP) eigentlich? Womit besch\\u00e4ftigen sich seine Mitglieder?\",\"poster\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/podlove\\\/image\\\/68747470733a2f2f7777772e7663702e64652f7066616466696e64656e2f77702d636f6e74656e742f75706c6f6164732f323031392f30382f706f64636173745f7066616466696e64656e2e6a7067\\\/500\\\/0\\\/0\\\/podcast-pfadfinden\",\"link\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\"},\"title\":\"Interview mit Prof. Dr. Gunda Voigts, Thema Gleichberechtigung und Jamboree Korea 2023\",\"subtitle\":\"\",\"summary\":\"In unserer neuen Folge wollen wir, auch wenn das Thema sicher nervt, noch einmal auf die Corona-Pandemie blicken und stellen die Frage, wie es Jugendlichen und Kindern in der Zeit der harten Lockdowns so ergangen ist. Dazu haben wir mit Prof. Dr. Gunda Voigts von der HAW Hamburg gesprochen. Au\\u00dferdem blicken wir auf das Thema Gleichberechtigung. Katharina und Leonie fragen sich, wie weit wir mit diesem Thema in unserer Gesellschaft stehen. Au\\u00dferdem gibt uns Steini vom BdP einen Einblick in das kommende Jamboree in Korea. Viel Spa\\u00df beim Anh\\u00f6ren w\\u00fcnscht euch die VCP Podcast-Redaktion.\",\"publicationDate\":\"2021-06-21T09:26:32+02:00\",\"duration\":\"00:38:52.604\",\"poster\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/podlove\\\/image\\\/68747470733a2f2f7777772e7663702e64652f7066616466696e64656e2f77702d636f6e74656e742f75706c6f6164732f323031392f30382f706f64636173745f7066616466696e64656e2e6a7067\\\/500\\\/0\\\/0\\\/podcast-pfadfinden\",\"link\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/podcast\\\/interview-mit-prof-dr-gunda-voigts-thema-gleichberechtigung-und-jamboree-korea-2023\\\/\",\"chapters\":[{\"start\":\"00:00:11.859\",\"title\":\"Begr\\u00fc\\u00dfung\",\"href\":\"\",\"image\":\"\"},{\"start\":\"00:00:57.202\",\"title\":\"Interview mit Prof. Dr. Gunda Voigts\",\"href\":\"https:\\\/\\\/www.haw-hamburg.de\\\/hochschule\\\/beschaeftigte\\\/detail\\\/person\\\/person\\\/show\\\/gunda-voigts\\\/172\\\/\",\"image\":\"\"},{\"start\":\"00:13:27.026\",\"title\":\"Thema Gleichberechtigung\",\"href\":\"https:\\\/\\\/www.vcp.de\\\/pfadfinden\\\/europaeische-jugendziele-gleichberechtigung-aller-geschlechter\\\/\",\"image\":\"\"},{\"start\":\"00:26:57.732\",\"title\":\"Jamboree Korea 2023\",\"href\":\"https:\\\/\\\/www.worldscoutjamboree.de\\\/\",\"image\":\"\"},{\"start\":\"00:37:47.711\",\"title\":\"Verabschiedung\",\"href\":\"\",\"image\":\"\"}],\"audio\":[{\"url\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/podlove\\\/file\\\/211\\\/s\\\/webplayer\\\/c\\\/website\\\/folge7_2021.mp3\",\"size\":\"32767495\",\"title\":\"MP3 Audio (mp3)\",\"mimeType\":\"audio\\\/mpeg\"}],\"files\":[{\"url\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/podlove\\\/file\\\/211\\\/s\\\/webplayer\\\/folge7_2021.mp3\",\"size\":\"32767495\",\"title\":\"MP3 Audio\",\"mimeType\":\"audio\\\/mpeg\"}]}}, {\"url\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/wp-json\\\/podlove-web-player\\\/shortcode\\\/config\\\/default\\\/theme\\\/default\",\"data\":{\"activeTab\":\"chapters\",\"subscribe-button\":null,\"share\":{\"channels\":[\"facebook\",\"twitter\",\"whats-app\",\"linkedin\",\"pinterest\",\"xing\",\"mail\",\"link\"],\"outlet\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/wp-content\\\/plugins\\\/podlove-web-player\\\/web-player\\\/share.html\",\"sharePlaytime\":true},\"related-episodes\":{\"source\":\"disabled\",\"value\":null},\"version\":5,\"theme\":{\"tokens\":{\"brand\":\"#E64415\",\"brandDark\":\"#235973\",\"brandDarkest\":\"#1A3A4A\",\"brandLightest\":\"#E9F1F5\",\"shadeDark\":\"#807E7C\",\"shadeBase\":\"#807E7C\",\"contrast\":\"#000\",\"alt\":\"#fff\"},\"fonts\":{\"ci\":{\"name\":\"ci\",\"family\":[\"-apple-system\",\"BlinkMacSystemFont\",\"Segoe UI\",\"Roboto\",\"Helvetica\",\"Arial\",\"sans-serif\",\"Apple Color Emoji\",\"Segoe UI Emoji\\\", \\\"Segoe UI Symbol\"],\"src\":[],\"weight\":800},\"regular\":{\"name\":\"regular\",\"family\":[\"-apple-system\",\"BlinkMacSystemFont\",\"Segoe UI\",\"Roboto\",\"Helvetica\",\"Arial\",\"sans-serif\",\"Apple Color Emoji\",\"Segoe UI Emoji\\\", \\\"Segoe UI Symbol\"],\"src\":[],\"weight\":300},\"bold\":{\"name\":\"bold\",\"family\":[\"-apple-system\",\"BlinkMacSystemFont\",\"Segoe UI\",\"Roboto\",\"Helvetica\",\"Arial\",\"sans-serif\",\"Apple Color Emoji\",\"Segoe UI Emoji\\\", \\\"Segoe UI Symbol\"],\"src\":[],\"weight\":700}}},\"base\":\"https:\\\/\\\/vcp.de\\\/pfadfinden\\\/wp-content\\\/plugins\\\/podlove-web-player\\\/web-player\\\/\"}}]);\n                podlovePlayer(player, \"https:\/\/vcp.de\/pfadfinden\/wp-json\/podlove-web-player\/shortcode\/publisher\/22060\", \"https:\/\/vcp.de\/pfadfinden\/wp-json\/podlove-web-player\/shortcode\/config\/default\/theme\/default\").then(function() {\n                  player && player.classList.remove(\"podlove-web-player-loading\");\n                });\n              });\n            <\/script>\n            <style>\n              .podlove-web-player.podlove-web-player-loading {\n                opacity: 0;\n              }\n            <\/style>\n        \n\t\n\t\t\n<p>In unserer neuen Folge wollen wir, auch wenn das Thema sicher nervt, noch einmal auf die Corona-Pandemie blicken und stellen die Frage, wie es Jugendlichen und Kindern in der Zeit der harten Lockdowns so ergangen ist. Dazu haben wir mit Prof. Dr. Gunda Voigts von der HAW Hamburg gesprochen. Au\u00dferdem blicken wir auf das Thema Gleichberechtigung. Katharina und Leonie fragen sich, wie weit wir mit diesem Thema in unserer Gesellschaft stehen. Au\u00dferdem gibt uns Steini vom BdP einen Einblick in das kommende Jamboree in Korea. Viel Spa\u00df beim Anh\u00f6ren w\u00fcnscht euch die VCP Podcast-Redaktion.<\/p>\n<h3>Inhalt<\/h3>\n<p>11.859790 Begr\u00fc\u00dfung<br \/>\n57.202472 <a href=\"https:\/\/www.haw-hamburg.de\/hochschule\/beschaeftigte\/detail\/person\/person\/show\/gunda-voigts\/172\/\" target=\"_blank\" rel=\"noopener\">Interview mit Prof. Dr. Gunda Voigts<\/a><br \/>\n807.026715 <a href=\"https:\/\/www.vcp.de\/pfadfinden\/europaeische-jugendziele-gleichberechtigung-aller-geschlechter\/\" target=\"_blank\" rel=\"noopener\">Thema Gleichberechtigung<\/a><br \/>\n1617.732705 <a href=\"https:\/\/www.worldscoutjamboree.de\/\" target=\"_blank\" rel=\"noopener\">Jamboree Korea 2023<\/a><br \/>\n2267.711799 Verabschiedung<\/p>\n","protected":false},"author":3,"featured_media":22059,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[353],"tags":[],"class_list":["post-22060","podcast","type-podcast","status-publish","has-post-thumbnail","hentry","category-podcast","post"],"acf":[],"_links":{"self":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/episodes\/22060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/episodes"}],"about":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/comments?post=22060"}],"version-history":[{"count":0,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/episodes\/22060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media\/22059"}],"wp:attachment":[{"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/media?parent=22060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/categories?post=22060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vcp.de\/pfadfinden\/wp-json\/wp\/v2\/tags?post=22060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}